{"id":19799,"date":"2021-03-17T17:23:53","date_gmt":"2021-03-17T16:23:53","guid":{"rendered":"https:\/\/my-iam.com\/?p=19799"},"modified":"2024-03-14T10:09:30","modified_gmt":"2024-03-14T09:09:30","slug":"microsoft-outlook-oder-teams","status":"publish","type":"post","link":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/","title":{"rendered":"Microsoft Outlook oder Teams &#8211; die Unterschiede"},"content":{"rendered":"<p>Mit der Einf\u00fchrung von Teams wird der Kommunikationsalltag ver\u00e4ndert. Vieles, was bisher per E-Mail ablief, kann oder wird bereits in MS Teams durchgef\u00fchrt. F\u00fcr viele Szenarien stellt sich die Frage: Ist Microsoft Outlook oder Teams die sinnvollere L\u00f6sung?<\/p>\n<p>Wir gehen dieser Frage in zwei Artikeln nach.<br \/>\n1. Artikel: <strong>Outlook oder Teams &#8211; die wesentlichen Unterschiede<\/strong><br \/>\n2. Artikel:\u00a0 <a href=\"https:\/\/my-iam.com\/teams-und-outlook-parallel-nutzen\/\" target=\"_blank\" rel=\"noopener\">Teams und Outlook parallel<\/a> &#8211; Gemeinsamkeiten und dualer Einsatz<\/p>\n<p><!--more--><\/p>\n\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-19805 size-full\" title=\"Outlook und Microsoft Teams - Die Unterschiede\" src=\"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/03\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png\" alt=\"Microsoft Outlook oder Teams - Aufgaben und Funktionen\" width=\"770\" height=\"462\" srcset=\"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/03\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png 770w, https:\/\/my-iam.com\/wp-content\/uploads\/2021\/03\/Outlook-vs.-Teams-Aufgaben-und-Funktionen-300x180.png 300w, https:\/\/my-iam.com\/wp-content\/uploads\/2021\/03\/Outlook-vs.-Teams-Aufgaben-und-Funktionen-768x461.png 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Index<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#Outlook_%E2%80%93_Klassische_Kommunikation_und_Selbstorganisation\" >Outlook &#8211; Klassische Kommunikation und Selbstorganisation<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#Klassische_Buerokommunikation\" >Klassische B\u00fcrokommunikation<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#Selbstorganisation_mit_Outlook\" >Selbstorganisation mit Outlook<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#Moeglichkeiten_der_Kooperation\" >M\u00f6glichkeiten der Kooperation<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#Microsoft_Teams_%E2%80%93_Teamarbeit_und_Informationsaustausch\" >Microsoft Teams &#8211; Teamarbeit und Informationsaustausch<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#Anwendungsbereich_von_Microsoft_Teams\" >Anwendungsbereich von Microsoft Teams<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#Umfassender_Informationsaustausch_zwischen_Kollegen\" >Umfassender Informationsaustausch zwischen Kollegen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#Erweiterbarkeit_und_Apps\" >Erweiterbarkeit und Apps<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#Unterschiede_in_der_Historie\" >Unterschiede in der Historie<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Outlook_%E2%80%93_Klassische_Kommunikation_und_Selbstorganisation\"><\/span>Outlook &#8211; Klassische Kommunikation und Selbstorganisation<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"Klassische_Buerokommunikation\"><\/span>Klassische B\u00fcrokommunikation<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Microsoft Outlook als Kommunikations-Hub f\u00fcr Mitarbeiter ist schnell erkl\u00e4rt. Externe und interne Kommunikation per <b>E-Mail und Telefon<\/b> ist der B\u00fcrostandard. Was nicht sofort m\u00fcndlich gekl\u00e4rt werden muss, kann per Mail organisiert werden. Outlook und sein technischer Gegenpart MS Exchange bzw. Exchange Online werden auch f\u00fcr Gruppenpostf\u00e4cher und E-Mail-Verteiler genutzt. Das ist aber nicht alles.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Selbstorganisation_mit_Outlook\"><\/span>Selbstorganisation mit Outlook<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Outlook ist auch ein Werkzeug f\u00fcr die Selbstorganisation. Neben dem <b>Kalender und Adressbuch, sind Aufgaben<\/b> (F\u00e4hnchen und Deadlines) ein wichtiger Bestandteil. E-Mails lassen sich in Aufgaben oder Termine umwandeln und in Unterordnern sortieren. Mit der <strong>farblichen Kategorisierungen f\u00fcr E-Mails und Termine<\/strong> kommt ein wichtiges Werkzeug der Selbstorganisation hinzu.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Moeglichkeiten_der_Kooperation\"><\/span>M\u00f6glichkeiten der Kooperation<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Nicht zuletzt wird Outlook f\u00fcr Info- und <b>Gemeinschaftspostf\u00e4cher<\/b> benutzt. Dort lassen sich auch Mails als Aufgaben darstellen und \u00fcber Kategorien zuordnen. Der Kalender wird zur gemeinsamen Terminvereinbarung verwendet. Es gibt<b> Ressourcenkalender<\/b> f\u00fcr R\u00e4ume und Beamer.<\/p>\n<p><b>Braucht man da noch Teams? <\/b><br \/>\nNun ja, zumindest hat Teams einen anderen Anwendungsfall.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Microsoft_Teams_%E2%80%93_Teamarbeit_und_Informationsaustausch\"><\/span>Microsoft Teams &#8211; Teamarbeit und Informationsaustausch<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Schauen wir uns die Kollaborationsplattform \u201cMicrosoft Teams\u201d oder kurz \u201cTeams\u201d genauer an. Am Beispiel eines Anwenders soll aufgezeigt werden, welche Themen bei der Einf\u00fchrung aus Mitarbeitersicht bedacht werden m\u00fcssen.<\/p>\n<p>Bei der Einf\u00fchrung von Microsoft Teams stellen sich zuerst die folgenden Fragen:<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li aria-level=\"1\">Wof\u00fcr benutze ich die neue Software?<\/li>\n<li aria-level=\"1\">Welchen Mehrwert bringt sie mir?<\/li>\n<li aria-level=\"1\"><b>Wie f\u00fcgt sich Teams neben Outlook in den Arbeitsalltag ein?<\/b><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Anwendungsbereich_von_Microsoft_Teams\"><\/span>Anwendungsbereich von Microsoft Teams<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Microsoft Teams ist eine Plattform, die sich auf den lockeren, informellen Gruppen- und Teamchat fokussiert. Es erm\u00f6glicht aber auch <b>unternehmens\u00fcbergreifende Projekt-Teams<\/b>. Mitarbeiter organisieren sich in Arbeits-Teams oder nutzen Chat-Gruppen, um innerhalb ihres (organisatorischen) Teams Informationen auszutauschen. \u00dcber die Chatfunktion hinaus, k\u00f6nnen Besprechungen organisiert, Videokonferenzen gestartet, Bildschirme und Dateien geteilt und gleichzeitig bearbeitet werden. Microsoft Teams ist also <b>eine Kollaborations-Plattform, die die Zusammenarbeit in und zwischen Teams erleichtern soll<\/b>.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Umfassender_Informationsaustausch_zwischen_Kollegen\"><\/span>Umfassender Informationsaustausch zwischen Kollegen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Der Mehrwert ist in der Theorie sogleich erkennbar: die wichtigsten Tools zur t\u00e4glichen Arbeit sind in einer Plattform geb\u00fcndelt. Informationen, Dateien und Links k\u00f6nnen in Gruppen oder Teams in Echtzeit ausgetauscht werden. Das Handling erinnert eher an soziale Netzwerke wie Facebook, LinkedIn oder Messenger, wie WhatsApp. <b>Die Nutzung von Teams ist insbesondere in Hinsicht auf die zunehmenden Remote Worker sinnvoll.<\/b><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Erweiterbarkeit_und_Apps\"><\/span>Erweiterbarkeit und Apps<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ein gro\u00dfer Unterschied zu Outlook ist, dass Teams erweitert und angepasst werden kann. Einem Kanal k\u00f6nnen Listen, Arbeitsdokumente und Tools wie Wikis, Notizb\u00fccher oder ganze Webseiten angehangen werden. Die Individualisierungsm\u00f6glichkeiten der Arbeitsgruppe sind hoch.<\/p>\n<p>Weiterhin bietet Microsoft Teams einen App Store an, in dem komplett neue Funktionen der Zusammenarbeit erg\u00e4nzt werden. <b>Apps wie my-IAM, bringen Nutzen f\u00fcr Anwender und Business, durch neue Services\u00a0<a href=\"https:\/\/my-iam.com\/peopleconnect\/\">PeopleConnect<\/a>.<\/b><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Unterschiede_in_der_Historie\"><\/span>Unterschiede in der Historie<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Um Outlook und Teams von ihren Anwendungsf\u00e4llen zu unterscheiden, macht es auch Sinn, die Historie beider zu sehen. Outlook gibt es seit den 1990ern, Teams seit 2016. Viele Anwendungsf\u00e4lle von Teams waren nie als Bestandteil von Mail-Kommunikation gedacht. Auf der anderen Seite wurde Outlook \u00fcber die Jahre um neue Features erweitert. Aus diesem Grund ist es heute auch kein einfacher Mail-Client mehr.<\/p>\n<p>Die Frage, ob Outlook oder Teams verwendet werden sollte, muss jede Organisation selbst beantworten. Aber <strong>der parallele Einsatz von Teams und Outlook bringt die meisten Vorteile<\/strong>. Zum einen sind beide \u00fcber Exchange Online miteinander verbunden, zum anderen k\u00f6nnen die klaren Unterschiede genutzt werden. Microsoft selbst sieht auch ein gemischtes Nutzungskonzept vor. Dazu mehr in Artikel zwei: <a href=\"https:\/\/my-iam.com\/teams-und-outlook-parallel-nutzen\/\" target=\"_blank\" rel=\"noopener\">Teams und Outlook parallel und sinnvoll nutzen<\/a>.<\/p>\n<p><a href=\"https:\/\/my-iam.com\/kontakt\/\"><button class=\"ButtonBeratung aligncenter\">Teams f\u00fcr alle mit my-IAM<\/button><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit der Einf\u00fchrung von Teams wird der Kommunikationsalltag ver\u00e4ndert. Vieles, was bisher per E-Mail ablief, kann oder wird bereits in [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3169],"tags":[3186,3170,3185],"class_list":["post-19799","post","type-post","status-publish","format-standard","hentry","category-microsoft-teams","tag-kollaboration","tag-microsoft-teams","tag-outlook"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Microsoft Outlook oder Teams - die Unterschiede - my-IAM<\/title>\n<meta name=\"description\" content=\"Sollten Outlook oder Teams f\u00fcr die Kommunikation eingesetzt werden? Teil 1 erkl\u00e4rt die Unterschiede beider Microsoft Apps.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Outlook oder Teams - die Unterschiede - my-IAM\" \/>\n<meta property=\"og:description\" content=\"Sollten Outlook oder Teams f\u00fcr die Kommunikation eingesetzt werden? Teil 1 erkl\u00e4rt die Unterschiede beider Microsoft Apps.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/\" \/>\n<meta property=\"og:site_name\" content=\"my-IAM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/firstattribute\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-17T16:23:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-14T09:09:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/03\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png\" \/>\n<meta name=\"author\" content=\"Sophia Tunui\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sophia Tunui\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/\"},\"author\":{\"name\":\"Sophia Tunui\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#\\\/schema\\\/person\\\/d6b8ee606d5147df1ed24cb2e2a0306b\"},\"headline\":\"Microsoft Outlook oder Teams &#8211; die Unterschiede\",\"datePublished\":\"2021-03-17T16:23:53+00:00\",\"dateModified\":\"2024-03-14T09:09:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/\"},\"wordCount\":683,\"publisher\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png\",\"keywords\":[\"Kollaboration\",\"Microsoft Teams\",\"Outlook\"],\"articleSection\":[\"Microsoft Teams\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/\",\"url\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/\",\"name\":\"Microsoft Outlook oder Teams - die Unterschiede - my-IAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png\",\"datePublished\":\"2021-03-17T16:23:53+00:00\",\"dateModified\":\"2024-03-14T09:09:30+00:00\",\"description\":\"Sollten Outlook oder Teams f\u00fcr die Kommunikation eingesetzt werden? Teil 1 erkl\u00e4rt die Unterschiede beider Microsoft Apps.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/#primaryimage\",\"url\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png\",\"contentUrl\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/microsoft-outlook-oder-teams\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/my-iam.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Outlook oder Teams &#8211; die Unterschiede\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/my-iam.com\\\/de\\\/\",\"name\":\"my-IAM\",\"description\":\"Cloud-Plattform f\u00fcr vernetztes Identity Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/my-iam.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#organization\",\"name\":\"my-IAM\",\"url\":\"https:\\\/\\\/my-iam.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-my-IAM-blau-512-150x150-2.png\",\"contentUrl\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-my-IAM-blau-512-150x150-2.png\",\"width\":200,\"height\":200,\"caption\":\"my-IAM\"},\"image\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/firstattribute\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#\\\/schema\\\/person\\\/d6b8ee606d5147df1ed24cb2e2a0306b\",\"name\":\"Sophia Tunui\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Microsoft Outlook oder Teams - die Unterschiede - my-IAM","description":"Sollten Outlook oder Teams f\u00fcr die Kommunikation eingesetzt werden? Teil 1 erkl\u00e4rt die Unterschiede beider Microsoft Apps.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/","og_locale":"de_DE","og_type":"article","og_title":"Microsoft Outlook oder Teams - die Unterschiede - my-IAM","og_description":"Sollten Outlook oder Teams f\u00fcr die Kommunikation eingesetzt werden? Teil 1 erkl\u00e4rt die Unterschiede beider Microsoft Apps.","og_url":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/","og_site_name":"my-IAM","article_publisher":"https:\/\/www.facebook.com\/firstattribute","article_published_time":"2021-03-17T16:23:53+00:00","article_modified_time":"2024-03-14T09:09:30+00:00","og_image":[{"url":"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/03\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png","type":"","width":"","height":""}],"author":"Sophia Tunui","twitter_misc":{"Verfasst von":"Sophia Tunui","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#article","isPartOf":{"@id":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/"},"author":{"name":"Sophia Tunui","@id":"https:\/\/my-iam.com\/de\/#\/schema\/person\/d6b8ee606d5147df1ed24cb2e2a0306b"},"headline":"Microsoft Outlook oder Teams &#8211; die Unterschiede","datePublished":"2021-03-17T16:23:53+00:00","dateModified":"2024-03-14T09:09:30+00:00","mainEntityOfPage":{"@id":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/"},"wordCount":683,"publisher":{"@id":"https:\/\/my-iam.com\/de\/#organization"},"image":{"@id":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#primaryimage"},"thumbnailUrl":"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/03\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png","keywords":["Kollaboration","Microsoft Teams","Outlook"],"articleSection":["Microsoft Teams"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/","url":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/","name":"Microsoft Outlook oder Teams - die Unterschiede - my-IAM","isPartOf":{"@id":"https:\/\/my-iam.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#primaryimage"},"image":{"@id":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#primaryimage"},"thumbnailUrl":"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/03\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png","datePublished":"2021-03-17T16:23:53+00:00","dateModified":"2024-03-14T09:09:30+00:00","description":"Sollten Outlook oder Teams f\u00fcr die Kommunikation eingesetzt werden? Teil 1 erkl\u00e4rt die Unterschiede beider Microsoft Apps.","breadcrumb":{"@id":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#primaryimage","url":"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/03\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png","contentUrl":"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/03\/Outlook-vs.-Teams-Aufgaben-und-Funktionen.png"},{"@type":"BreadcrumbList","@id":"https:\/\/my-iam.com\/de\/microsoft-outlook-oder-teams\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/my-iam.com\/de\/"},{"@type":"ListItem","position":2,"name":"Microsoft Outlook oder Teams &#8211; die Unterschiede"}]},{"@type":"WebSite","@id":"https:\/\/my-iam.com\/de\/#website","url":"https:\/\/my-iam.com\/de\/","name":"my-IAM","description":"Cloud-Plattform f\u00fcr vernetztes Identity Management","publisher":{"@id":"https:\/\/my-iam.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/my-iam.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/my-iam.com\/de\/#organization","name":"my-IAM","url":"https:\/\/my-iam.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/my-iam.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/07\/Logo-my-IAM-blau-512-150x150-2.png","contentUrl":"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/07\/Logo-my-IAM-blau-512-150x150-2.png","width":200,"height":200,"caption":"my-IAM"},"image":{"@id":"https:\/\/my-iam.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/firstattribute"]},{"@type":"Person","@id":"https:\/\/my-iam.com\/de\/#\/schema\/person\/d6b8ee606d5147df1ed24cb2e2a0306b","name":"Sophia Tunui"}]}},"_links":{"self":[{"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/posts\/19799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/comments?post=19799"}],"version-history":[{"count":28,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/posts\/19799\/revisions"}],"predecessor-version":[{"id":27331,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/posts\/19799\/revisions\/27331"}],"wp:attachment":[{"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/media?parent=19799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/categories?post=19799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/tags?post=19799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}