{"id":28727,"date":"2024-09-10T11:08:34","date_gmt":"2024-09-10T09:08:34","guid":{"rendered":"https:\/\/my-iam.com\/?p=28727"},"modified":"2024-09-16T14:05:40","modified_gmt":"2024-09-16T12:05:40","slug":"verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen","status":"publish","type":"post","link":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/","title":{"rendered":"Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen"},"content":{"rendered":"<p>Viele Unternehmen m\u00f6chten Identit\u00e4tsdaten und Kontakte f\u00fcr Low-Code-Anwendungen, wie Mendix, nutzen. In unserem konkreten Anwendungsfall sollte Mendix ein in die Jahre gekommenes Organisationsverzeichnis ersetzen.<\/p>\n<p>Doch die Identit\u00e4tsdaten sind normalerweise nicht an einer Stelle verf\u00fcgbar. Sie liegen verteilt in verschiedenen Datenbanken und Verzeichnissen. Mittels des <a href=\"https:\/\/my-iam.com\/realidentity\/\">my-IAM RealIdentity<\/a> Services lassen sich Identit\u00e4ten aller Art zentral b\u00fcndeln und an Mendix weitergeben. Wie das in der Praxis umgesetzt wurde, erfahren Sie hier.<\/p>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Index<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#Mendix_und_Identitaetsinformationen\" >Mendix und Identit\u00e4tsinformationen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#Identitaetsdaten_fuer_Mendix-Anwendung_bereitstellen\" >Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung bereitstellen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#Loesung_Identitaets-_Kontakt-_und_Team-Integration_mittels_my-IAM\" >L\u00f6sung: Identit\u00e4ts-, Kontakt- und Team-Integration mittels my-IAM<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#Vorteile_von_Mendix_in_Kombination_mit_my-IAM_RealIdentity\" >Vorteile von Mendix in Kombination mit my-IAM RealIdentity<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#Zusammenfassung\" >Zusammenfassung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#Mehr_zur_my-IAM_platform\" >Mehr zur my-IAM platform<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Mendix_und_Identitaetsinformationen\"><\/span>Mendix und Identit\u00e4tsinformationen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Viele Unternehmen nutzen Mendix als Low-Code-Plattform, um schnell individuelle und passgenaue Apps und Anwendungen f\u00fcr ihre Anwender zu entwickeln. Mendix selbst bezeichnet sich als die f\u00fchrende Plattform zur Entwicklung von Unternehmensanwendungen.<\/p>\n<p><strong>In nahezu jeder neuartigen Anwendung werden Mitarbeiterkontakte, Kundenkontakte, Partnerkontakte, Teaminformationen, Standortinformationen oder sonstige Identit\u00e4tsinformationen ben\u00f6tigt oder verarbeitet.<\/strong><\/p>\n<p>Doch wie bekommt ein Unternehmen diese vielen Daten geb\u00fcndelt in eine neue Mendix-Anwendung?<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Identitaetsdaten_fuer_Mendix-Anwendung_bereitstellen\"><\/span>Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung bereitstellen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Wir berichten von einem <strong>Praxisfall<\/strong> einer unserer Kunden: <br \/>\nDieser ehemalige Notes-Anwender hatte in der Vergangenheit ein spezielles <strong>Organisationsverzeichnis auf Notes-Basis<\/strong>, welches sehr individuell auf das Unternehmen zugeschnitten war. Das System war veraltet, beinhaltete nicht mehr alle Identit\u00e4ten und Kontaktinformationen und war zudem nur On-Premises verf\u00fcgbar.<\/p>\n<p>Das Unternehmen entschloss sich dazu, diesen speziellen Anwendungsfall mittels einer Mendix-Anwendung zu l\u00f6sen.\u00a0<\/p>\n<p>Es zeigte sich, dass die notwendigen Oberfl\u00e4chen mittels Mendix relativ schnell geschaffen werden k\u00f6nnen. Ein SSO mittels OAuth (ENTRA) konnte ebenfalls integriert werden. Die Erwartungen waren hoch, da die Mockups der Oberfl\u00e4che sehr ansprechend aussahen.\u00a0<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-29103 size-large\" title=\"Identit\u00e4tsdaten werden f\u00fcr Mendix-Anwendung gebraucht\" src=\"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png\" alt=\"Identit\u00e4tsdaten werden f\u00fcr Mendix-Anwendung gebraucht\" width=\"1024\" height=\"530\" srcset=\"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png 1024w, https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-300x155.png 300w, https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-768x398.png 768w, https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1536x795.png 1536w, https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-2048x1060.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Bei genauer Betrachtung zeigte sich, <strong>dass die notwendigen Identit\u00e4ts-, Kontakt- und Rolleninformationen in unterschiedlichen Systemen verteilt waren<\/strong>. Denn mittlerweile galt es, Identit\u00e4tsinformationen aus ENTRA, Active Directory, HR-System, Org-Management-System, CRM-System und einem speziellen ERP-System zusammenzuf\u00fchren.<\/p>\n<p>Die erweiterten Anforderungen erforderten eine Art Logik-Ebene, die Mendix all die Informationen permanent und aktuell bereitstellen kann.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Loesung_Identitaets-_Kontakt-_und_Team-Integration_mittels_my-IAM\"><\/span>L\u00f6sung: Identit\u00e4ts-, Kontakt- und Team-Integration mittels my-IAM<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Bei der Suche nach einer Probleml\u00f6sung sind die Mendix-Entwickler auf den Business Service <a href=\"https:\/\/my-iam.com\/realidentity\/\">my-IAM RealIdentity<\/a> gesto\u00dfen. Bei my-IAM RealIdentity handelt es sich um einen SaaS Cloud Service, der f\u00fcr ein Unternehmen s\u00e4mtliche Identit\u00e4ten, wie beispielsweise Mitarbeiter, Kunden, Partner, Lieferanten zusammenf\u00fchren, managen und bereitstellen kann.<\/p>\n<p><strong>my-IAM RealIdentity ist kein klassisches IAM-System, sondern eine neuartige SaaS L\u00f6sung zur Bereitstellung und Management von Identit\u00e4ten aller Art f\u00fcr nahezu alle Arten von Anwendungen oder Apps.<\/strong><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-28842 size-large\" title=\"my-IAM Realldentity stellt Identit\u00e4tsdaten f\u00fcr Mendix bereit\" src=\"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Auf-alle-Identitaetsdaten-zugreifen-my-IAM-RealIdentity-1024x530.png\" alt=\"my-IAM Realldentity stellt Identit\u00e4tsdaten f\u00fcr Mendix bereit\" width=\"1024\" height=\"530\" srcset=\"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Auf-alle-Identitaetsdaten-zugreifen-my-IAM-RealIdentity-1024x530.png 1024w, https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Auf-alle-Identitaetsdaten-zugreifen-my-IAM-RealIdentity-300x155.png 300w, https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Auf-alle-Identitaetsdaten-zugreifen-my-IAM-RealIdentity-768x398.png 768w, https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Auf-alle-Identitaetsdaten-zugreifen-my-IAM-RealIdentity-1536x795.png 1536w, https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Auf-alle-Identitaetsdaten-zugreifen-my-IAM-RealIdentity-2048x1060.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Eine Besonderheit ist, dass my-IAM RealIdentity <strong>voll in ENTRA integriert<\/strong> ist und sich dar\u00fcber hinaus leicht in weitere Systeme, wie beispielsweise SAP SucessFactors oder einem CRM-System integrieren l\u00e4sst. Anders als klassische IDM-Systeme, ist es nicht notwendig, dass das Management aller Identit\u00e4tsarten und Informationen \u00fcber my-IAM RealIdentity laufen.<\/p>\n<p>Das macht eine schrittweise oder Teileinf\u00fchrung m\u00f6glich. Bestehende effiziente Prozesse zum Identit\u00e4tsmanagement k\u00f6nnen weiter genutzt werden. Gleichzeit k\u00f6nnen neuartige Anwendungen alle Identit\u00e4ten nutzen, nicht nur die in ENTRA oder im Active Directory stehen.<\/p>\n<p><strong>Es zeigte sich schnell, dass die Kombination einer kundenspezifischen Mendix-Anwendung mit my-IAM als eine Art Identity Information Broker die ideale L\u00f6sung ist.<\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Vorteile_von_Mendix_in_Kombination_mit_my-IAM_RealIdentity\"><\/span><span class=\"cf0\">Vorteile von Mendix in Kombination mit my-IAM RealIdentity<\/span><!--EndFragment --><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Zuerst dachten die Mendix-Entwickler, dass sie sich die notwendigen Identit\u00e4tsinformationen aus RealIdentity ziehen und in eine eigene Datenbank \u00fcbertragen. Das ist nicht notwendig, da RealIdentity mehr als ein Identit\u00e4tsspeicher ist.<\/p>\n<p>Dies waren konkrete Anforderungen des Unternehmens:<\/p>\n<ul style=\"list-style-type: square;\">\n<li>Von Mendix aus sollte es m\u00f6glich sein, nach Identit\u00e4ten, Kontakten, Kunden oder Partnern zu suchen. Am besten relativ frei und mit einer gewissen Intelligenz.<\/li>\n<li>Neben der smarten Suche, war es auch wichtig, dass nicht alle Anwender alle Informationen sehen oder bearbeiten k\u00f6nnen. Sales-Mitarbeiter einer Region sollten beispielsweise nur Partnerkontakte einer gewissen Region sehen.<\/li>\n<li>Das Ganze sollte nat\u00fcrlich hochverf\u00fcgbar, performant und in der gesamten Welt zugreifbar sein.<\/li>\n<\/ul>\n<p><strong>Die SaaS-L\u00f6sung RealIdentity kann nahezu jede beliebige Art von Identit\u00e4ten, mit den unterschiedlichsten Eigenschaften und Attributen zur Verf\u00fcgen stellen.<\/strong> Die RealIdentity API verf\u00fcgt \u00fcber eine <strong>Smart-Search Suchfunktion<\/strong> (\u00e4hnlich wie die Google-Suche) und<strong> speziellen Authorization- oder Such-Filterfunktionen<\/strong>, um ein positives Benutzererlebnis zu erzielen.\u00a0Gerade LowCode-Anwendungen wie Mendix, ben\u00f6tigen intelligente Services, um das beste Benutzererlebnis zu erzielen.<\/p>\n<p>Ein weiterer Vorteil des my-IAM RealIdentity Service ist, dass eine \u00c4nderung der Identit\u00e4ten oder Kontakte m\u00f6glich ist.<\/p>\n<p>Das Ergebnis ist, dass die neu geschaffene Anwendung direkt auf die RealIdentity API zugreift. Das minimiert die Komplexit\u00e4t innerhalb der Mendix-Anwendung und beschleunigt die Entwicklungszeit.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Zusammenfassung\"><\/span>Zusammenfassung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Durch die <strong>Kombination von Mendix mit my-IAM RealIdentity<\/strong> konnte z\u00fcgig eine individuelle Unternehmensl\u00f6sung geschaffen werden, welche die Anforderung an die digitale Transformation voll erf\u00fcllt.<\/p>\n<p>Es wurde das Beste aus beiden Welten genutzt:<\/p>\n<p>1. Die <strong>Individualit\u00e4t<\/strong>, die <strong>z\u00fcgige Entwicklung<\/strong>\u00a0und das <strong>hervorragende Benutzererlebnis <\/strong>mittels Mendix<\/p>\n<p>2. Die <strong>Nutzung aller Identit\u00e4ten<\/strong> (Mitarbeiter, Kunden, Partner, Lieferanten), die<strong> smarte Suche<\/strong>, die <strong>hohe Sicherheit<\/strong>\u00a0 und die Zukunftsf\u00e4higkeit was den Ausbau des Identit\u00e4tsmanagements betrifft mittels my-IAM RealIdentity<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Mehr_zur_my-IAM_platform\"><\/span>Mehr zur my-IAM platform<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img decoding=\"async\" class=\"alignleft wp-image-28423\" title=\"my-IAM platform\" src=\"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/08\/my-IAM-platform-logo-210x300.png\" alt=\"my-IAM platform\" width=\"110\" height=\"157\" srcset=\"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/08\/my-IAM-platform-logo-210x300.png 210w, https:\/\/my-iam.com\/wp-content\/uploads\/2024\/08\/my-IAM-platform-logo.png 491w\" sizes=\"(max-width: 110px) 100vw, 110px\" \/>Die my-IAM platform <strong>vereint s\u00e4mtliche Identit\u00e4ten aus verschiedenen Quellsystemen<\/strong> und\u00a0<strong>macht sie f\u00fcr Anwendungen und Apps jeder Art nutzbar<\/strong>. Neben der MS Teams-integrierten App <a href=\"https:\/\/my-iam.com\/peopleconnect\/\">my-IAM PeopleConnect<\/a>, umfasst sie die Business Services <a href=\"https:\/\/my-iam.com\/realidentity\/\">my-IAM RealIdentity<\/a> und <a href=\"https:\/\/my-iam.com\/realgroup\/\">my-IAM RealGroup<\/a>.<\/p>\n<p><a href=\"https:\/\/my-iam.com\/demo-buchen\/\" rel=\"noopener\"><button class=\"ButtonBeratung2 aligncenter\">Jetzt Online-Demo buchen<\/button><\/a><\/p>\n<p style=\"text-align: center;\">Sie k\u00f6nnen unser Team auch telefonisch erreichen unter<br \/>\n<a href=\"tel:+4981969984330\"><strong>+49 8196 998 4330<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viele Unternehmen m\u00f6chten Identit\u00e4tsdaten und Kontakte f\u00fcr Low-Code-Anwendungen, wie Mendix, nutzen. In unserem konkreten Anwendungsfall sollte Mendix ein in die [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3393,1],"tags":[3420],"class_list":["post-28727","post","type-post","status-publish","format-standard","hentry","category-my-iam-realidentity","category-neuigkeiten","tag-mendix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen - my-IAM<\/title>\n<meta name=\"description\" content=\"Wie Sie unterschiedliche Identit\u00e4tsdaten f\u00fcr eine Mendix-Anwendung nutzen k\u00f6nnen: my-IAM RealIdentity stellt Daten aus vielen Quellen bereit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen - my-IAM\" \/>\n<meta property=\"og:description\" content=\"Wie Sie unterschiedliche Identit\u00e4tsdaten f\u00fcr eine Mendix-Anwendung nutzen k\u00f6nnen: my-IAM RealIdentity stellt Daten aus vielen Quellen bereit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/\" \/>\n<meta property=\"og:site_name\" content=\"my-IAM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/firstattribute\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-10T09:08:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T12:05:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png\" \/>\n<meta name=\"author\" content=\"Sophia Tunui\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sophia Tunui\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/\"},\"author\":{\"name\":\"Sophia Tunui\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#\\\/schema\\\/person\\\/d6b8ee606d5147df1ed24cb2e2a0306b\"},\"headline\":\"Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen\",\"datePublished\":\"2024-09-10T09:08:34+00:00\",\"dateModified\":\"2024-09-16T12:05:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/\"},\"wordCount\":868,\"publisher\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png\",\"keywords\":[\"Mendix\"],\"articleSection\":[\"my-IAM RealIdentity\",\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/\",\"url\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/\",\"name\":\"Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen - my-IAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png\",\"datePublished\":\"2024-09-10T09:08:34+00:00\",\"dateModified\":\"2024-09-16T12:05:40+00:00\",\"description\":\"Wie Sie unterschiedliche Identit\u00e4tsdaten f\u00fcr eine Mendix-Anwendung nutzen k\u00f6nnen: my-IAM RealIdentity stellt Daten aus vielen Quellen bereit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png\",\"contentUrl\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/my-iam.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/my-iam.com\\\/de\\\/\",\"name\":\"my-IAM\",\"description\":\"Cloud-Plattform f\u00fcr vernetztes Identity Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/my-iam.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#organization\",\"name\":\"my-IAM\",\"url\":\"https:\\\/\\\/my-iam.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-my-IAM-blau-512-150x150-2.png\",\"contentUrl\":\"https:\\\/\\\/my-iam.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-my-IAM-blau-512-150x150-2.png\",\"width\":200,\"height\":200,\"caption\":\"my-IAM\"},\"image\":{\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/firstattribute\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/my-iam.com\\\/de\\\/#\\\/schema\\\/person\\\/d6b8ee606d5147df1ed24cb2e2a0306b\",\"name\":\"Sophia Tunui\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen - my-IAM","description":"Wie Sie unterschiedliche Identit\u00e4tsdaten f\u00fcr eine Mendix-Anwendung nutzen k\u00f6nnen: my-IAM RealIdentity stellt Daten aus vielen Quellen bereit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/","og_locale":"de_DE","og_type":"article","og_title":"Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen - my-IAM","og_description":"Wie Sie unterschiedliche Identit\u00e4tsdaten f\u00fcr eine Mendix-Anwendung nutzen k\u00f6nnen: my-IAM RealIdentity stellt Daten aus vielen Quellen bereit.","og_url":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/","og_site_name":"my-IAM","article_publisher":"https:\/\/www.facebook.com\/firstattribute","article_published_time":"2024-09-10T09:08:34+00:00","article_modified_time":"2024-09-16T12:05:40+00:00","og_image":[{"url":"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png","type":"","width":"","height":""}],"author":"Sophia Tunui","twitter_misc":{"Verfasst von":"Sophia Tunui","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#article","isPartOf":{"@id":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/"},"author":{"name":"Sophia Tunui","@id":"https:\/\/my-iam.com\/de\/#\/schema\/person\/d6b8ee606d5147df1ed24cb2e2a0306b"},"headline":"Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen","datePublished":"2024-09-10T09:08:34+00:00","dateModified":"2024-09-16T12:05:40+00:00","mainEntityOfPage":{"@id":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/"},"wordCount":868,"publisher":{"@id":"https:\/\/my-iam.com\/de\/#organization"},"image":{"@id":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#primaryimage"},"thumbnailUrl":"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png","keywords":["Mendix"],"articleSection":["my-IAM RealIdentity","News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/","url":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/","name":"Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen - my-IAM","isPartOf":{"@id":"https:\/\/my-iam.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#primaryimage"},"image":{"@id":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#primaryimage"},"thumbnailUrl":"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png","datePublished":"2024-09-10T09:08:34+00:00","dateModified":"2024-09-16T12:05:40+00:00","description":"Wie Sie unterschiedliche Identit\u00e4tsdaten f\u00fcr eine Mendix-Anwendung nutzen k\u00f6nnen: my-IAM RealIdentity stellt Daten aus vielen Quellen bereit.","breadcrumb":{"@id":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#primaryimage","url":"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png","contentUrl":"https:\/\/my-iam.com\/wp-content\/uploads\/2024\/09\/Keine-Identitaetsdaten-in-Mendix-Anwendung-1024x530.png"},{"@type":"BreadcrumbList","@id":"https:\/\/my-iam.com\/de\/verschiedene-identitaetsdaten-fuer-mendix-anwendung-nutzen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/my-iam.com\/de\/"},{"@type":"ListItem","position":2,"name":"Verschiedene Identit\u00e4tsdaten f\u00fcr Mendix-Anwendung nutzen"}]},{"@type":"WebSite","@id":"https:\/\/my-iam.com\/de\/#website","url":"https:\/\/my-iam.com\/de\/","name":"my-IAM","description":"Cloud-Plattform f\u00fcr vernetztes Identity Management","publisher":{"@id":"https:\/\/my-iam.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/my-iam.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/my-iam.com\/de\/#organization","name":"my-IAM","url":"https:\/\/my-iam.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/my-iam.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/07\/Logo-my-IAM-blau-512-150x150-2.png","contentUrl":"https:\/\/my-iam.com\/wp-content\/uploads\/2021\/07\/Logo-my-IAM-blau-512-150x150-2.png","width":200,"height":200,"caption":"my-IAM"},"image":{"@id":"https:\/\/my-iam.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/firstattribute"]},{"@type":"Person","@id":"https:\/\/my-iam.com\/de\/#\/schema\/person\/d6b8ee606d5147df1ed24cb2e2a0306b","name":"Sophia Tunui"}]}},"_links":{"self":[{"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/posts\/28727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/comments?post=28727"}],"version-history":[{"count":28,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/posts\/28727\/revisions"}],"predecessor-version":[{"id":29125,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/posts\/28727\/revisions\/29125"}],"wp:attachment":[{"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/media?parent=28727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/categories?post=28727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-iam.com\/de\/wp-json\/wp\/v2\/tags?post=28727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}